{"id":13131,"date":"2024-07-08T12:45:49","date_gmt":"2024-07-08T10:45:49","guid":{"rendered":"https:\/\/visitmarratxi.es\/?post_type=event&#038;p=13131"},"modified":"2024-07-08T13:54:07","modified_gmt":"2024-07-08T11:54:07","slug":"la-1ere-carrera-del-fang-2024","status":"publish","type":"event","link":"https:\/\/visitmarratxi.es\/fr\/event\/la-1ere-carrera-del-fang-2024\/","title":{"rendered":"La 1\u00e8re \u00ab\u00a0Carrera del Fang\u00a0\u00bb 2024"},"content":{"rendered":"<p>La course, qui aura lieu le 20 juillet, partira de la Pla\u00e7a de Can Flor, \u00e0 P\u00f2rtol, et parcourra les poteries et poteries les plus embl\u00e9matiques de la ville, offrant une exp\u00e9rience unique qui met en valeur le riche patrimoine c\u00e9ramique de Marratx\u00ed.<\/p>\n<p>Il y aura quatre modes : un premier comp\u00e9titif de 7 kilom\u00e8tres et demi, un second de 3 kilom\u00e8tres populaires, sans podium et sans \u00eatre comp\u00e9titif pour ceux qui veulent se lancer dans le monde du running. Ces 3 kilom\u00e8tres peuvent \u00e9galement se faire en marchant de mani\u00e8re plus ludique. Avant cela, des courses pour enfants seront organis\u00e9es pour les enfants jusqu&rsquo;\u00e0 12 ans, avec diff\u00e9rentes distances plus courtes et gratuites.<\/p>\n<figure class=\"wp-block-image size-large\"><a class=\"td-modal-image\" href=\"https:\/\/www.mtxi.es\/wp-content\/uploads\/2024\/07\/A0_Cursa-del-fang_page-0001-2-724x1024.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-18238 aligncenter\" src=\"https:\/\/www.mtxi.es\/wp-content\/uploads\/2024\/07\/A0_Cursa-del-fang_page-0001-2-724x1024.jpg\" sizes=\"auto, (max-width: 724px) 100vw, 724px\" srcset=\"https:\/\/www.mtxi.es\/wp-content\/uploads\/2024\/07\/A0_Cursa-del-fang_page-0001-2-724x1024.jpg 724w, https:\/\/www.mtxi.es\/wp-content\/uploads\/2024\/07\/A0_Cursa-del-fang_page-0001-2-212x300.jpg 212w, https:\/\/www.mtxi.es\/wp-content\/uploads\/2024\/07\/A0_Cursa-del-fang_page-0001-2-768x1086.jpg 768w, https:\/\/www.mtxi.es\/wp-content\/uploads\/2024\/07\/A0_Cursa-del-fang_page-0001-2-1086x1536.jpg 1086w, https:\/\/www.mtxi.es\/wp-content\/uploads\/2024\/07\/A0_Cursa-del-fang_page-0001-2-1449x2048.jpg 1449w, https:\/\/www.mtxi.es\/wp-content\/uploads\/2024\/07\/A0_Cursa-del-fang_page-0001-2-696x984.jpg 696w, https:\/\/www.mtxi.es\/wp-content\/uploads\/2024\/07\/A0_Cursa-del-fang_page-0001-2-1392x1968.jpg 1392w, https:\/\/www.mtxi.es\/wp-content\/uploads\/2024\/07\/A0_Cursa-del-fang_page-0001-2-1068x1510.jpg 1068w, https:\/\/www.mtxi.es\/wp-content\/uploads\/2024\/07\/A0_Cursa-del-fang_page-0001-2-1920x2714.jpg 1920w, https:\/\/www.mtxi.es\/wp-content\/uploads\/2024\/07\/A0_Cursa-del-fang_page-0001-2-150x212.jpg 150w, https:\/\/www.mtxi.es\/wp-content\/uploads\/2024\/07\/A0_Cursa-del-fang_page-0001-2-scaled.jpg 1811w\" alt=\"\" width=\"724\" height=\"1024\" \/><\/a><\/figure>\n<p>&nbsp;<\/p>\n<p>Cet \u00e9v\u00e9nement offrira non seulement une fa\u00e7on amusante et saine de c\u00e9l\u00e9brer les f\u00eates du Carmel, mais sera \u00e9galement l&rsquo;occasion de mettre en valeur le travail des artisans locaux et la beaut\u00e9 de leurs produits. La Cursa del Fang est une manifestation de la fiert\u00e9 de Marratx\u00ed pour son patrimoine c\u00e9ramique.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>D\u00e9tails de l&rsquo;\u00e9v\u00e9nement<\/strong><\/p>\n<p>\u2013 <strong>Date et heure de la course :<\/strong> 20 juillet, 19h00<\/p>\n<p>\u2013 Courses pour enfants. gratuit<\/p>\n<p>\u2013 Course de 7,5 km. 7 euros<\/p>\n<p>\u2013 Course et marche non comp\u00e9titive de 3 km. 5 euros<\/p>\n<p>\u2013 <strong>Informations et inscriptions<\/strong><\/p>\n<p><a href=\"elitechip.com\" target=\"_blank\" rel=\"noopener\">www.elitechip.com<\/a> et sur les r\u00e9seaux sociaux <a href=\"https:\/\/www.instagram.com\/cursadelfang\/\" target=\"_blank\" rel=\"noopener\">@cursadelfang<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La course, qui aura lieu le 20 juillet, partira de la Pla\u00e7a de Can Flor, \u00e0 P\u00f2rtol, et parcourra les poteries et poteries les plus embl\u00e9matiques de la ville, offrant une exp\u00e9rience unique qui met en valeur le riche patrimoine&#8230;<\/p>\n","protected":false},"author":6,"featured_media":13096,"comment_status":"open","ping_status":"closed","template":"","meta":{"footnotes":""},"eventcat":[696,716],"organizer":[],"event_tags":[680],"location":[765,613],"class_list":["post-13131","event","type-event","status-publish","has-post-thumbnail","hentry","eventcat-activites","eventcat-des-sports","event_tags-evenement","location-placa-can-flor-2","location-portol-fr"],"_links":{"self":[{"href":"https:\/\/visitmarratxi.es\/fr\/wp-json\/wp\/v2\/event\/13131","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visitmarratxi.es\/fr\/wp-json\/wp\/v2\/event"}],"about":[{"href":"https:\/\/visitmarratxi.es\/fr\/wp-json\/wp\/v2\/types\/event"}],"author":[{"embeddable":true,"href":"https:\/\/visitmarratxi.es\/fr\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/visitmarratxi.es\/fr\/wp-json\/wp\/v2\/comments?post=13131"}],"version-history":[{"count":1,"href":"https:\/\/visitmarratxi.es\/fr\/wp-json\/wp\/v2\/event\/13131\/revisions"}],"predecessor-version":[{"id":13132,"href":"https:\/\/visitmarratxi.es\/fr\/wp-json\/wp\/v2\/event\/13131\/revisions\/13132"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visitmarratxi.es\/fr\/wp-json\/wp\/v2\/media\/13096"}],"wp:attachment":[{"href":"https:\/\/visitmarratxi.es\/fr\/wp-json\/wp\/v2\/media?parent=13131"}],"wp:term":[{"taxonomy":"eventcat","embeddable":true,"href":"https:\/\/visitmarratxi.es\/fr\/wp-json\/wp\/v2\/eventcat?post=13131"},{"taxonomy":"organizer","embeddable":true,"href":"https:\/\/visitmarratxi.es\/fr\/wp-json\/wp\/v2\/organizer?post=13131"},{"taxonomy":"event_tags","embeddable":true,"href":"https:\/\/visitmarratxi.es\/fr\/wp-json\/wp\/v2\/event_tags?post=13131"},{"taxonomy":"location","embeddable":true,"href":"https:\/\/visitmarratxi.es\/fr\/wp-json\/wp\/v2\/location?post=13131"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}